{"id":7219,"date":"2016-08-07T08:18:45","date_gmt":"2016-08-07T08:18:45","guid":{"rendered":"http:\/\/localhost\/test\/2016\/08\/07\/%d8%aa%d8%b4%d8%b1%d9%81-%d9%85%d8%b1%d8%af-%d8%b5%d8%a7%d8%a8%d9%88%d9%86%db%8c\/"},"modified":"2016-08-07T08:18:45","modified_gmt":"2016-08-07T08:18:45","slug":"%d8%aa%d8%b4%d8%b1%d9%81-%d9%85%d8%b1%d8%af-%d8%b5%d8%a7%d8%a8%d9%88%d9%86%db%8c","status":"publish","type":"post","link":"https:\/\/shiastudies.com\/fa\/%d8%aa%d8%b4%d8%b1%d9%81-%d9%85%d8%b1%d8%af-%d8%b5%d8%a7%d8%a8%d9%88%d9%86%db%8c\/","title":{"rendered":"\u062a\u0634\u0631\u0641 \u0645\u0631\u062f \u0635\u0627\u0628\u0648\u0646\u06cc"},"content":{"rendered":"<p>\u0634\u062e\u0635 \u0639\u0637\u0651\u0627\u0631\u06cc \u0627\u0632 \u0627\u0647\u0644 \u0628\u0635\u0631\u0647 \u0645\u06cc&zwnj;\u06af\u0648\u06cc\u062f: \u0631\u0648\u0632\u06cc \u062f\u0631 \u0645\u063a\u0627\u0632\u0629 \u0639\u0637\u0651\u0627\u0631\u06cc\u0645 \u0646\u0634\u0633\u062a\u0647 \u0628\u0648\u062f\u0645 \u06a9\u0647 \u062f\u0648 \u0646\u0641\u0631 \u0628\u0631\u0627\u06cc \u062e\u0631\u06cc\u062f\u0646 \u0633\u062f\u0631 \u0648 \u06a9\u0627\u0641\u0648\u0631 \u0628\u0647 \u062f\u06a9\u0651\u0627\u0646 \u0645\u0646 \u0648\u0627\u0631\u062f \u0634\u062f\u0646\u062f. \u0648\u0642\u062a\u06cc \u0628\u0647 \u0637\u0631\u0632 \u0635\u062d\u0628\u062a \u06a9\u0631\u062f\u0646 \u0648 \u0686\u0647\u0631\u0647&zwnj;\u0647\u0627\u06cc\u0634\u0627\u0646 \u062f\u0642\u0651\u062a \u06a9\u0631\u062f\u0645\u060c \u0645\u062a\u0648\u062c\u0651\u0647 \u0634\u062f\u0645 \u06a9\u0647 \u0627\u0647\u0644 \u0628\u0635\u0631\u0647 \u0648 \u0628\u0644\u06a9\u0647 \u0627\u0632 \u0645\u0631\u062f\u0645 \u0645\u0639\u0645\u0648\u0644\u06cc \u0646\u06cc\u0633\u062a\u0646\u062f \u0628\u0647 \u0647\u0645\u06cc\u0646 \u062c\u0647\u062a \u0627\u0632 \u0634\u0647\u0631 \u0648 \u062f\u06cc\u0627\u0631\u0634\u0627\u0646 \u067e\u0631\u0633\u06cc\u062f\u0645\u060c \u0648\u0644\u06cc \u062c\u0648\u0627\u0628\u06cc \u0646\u062f\u0627\u062f\u0646\u062f.<br \/>\n\u0645\u0646 \u0627\u0635\u0631\u0627\u0631 \u0645\u06cc&zwnj;\u06a9\u0631\u062f\u0645\u060c \u0648\u0644\u06cc \u062c\u0648\u0627\u0628\u06cc \u0646\u0645\u06cc&zwnj;\u062f\u0627\u062f\u0646\u062f.\u0628\u0647 \u0647\u0631 \u062d\u0627\u0644 \u0645\u0646 \u0627\u0644\u062a\u0645\u0627\u0633 \u0646\u0645\u0648\u062f\u0645\u060c \u062a\u0627 \u0622\u0646\u06a9\u0647 \u0622\u0646\u0647\u0627 \u0631\u0627 \u0628\u0647 \u0631\u0633\u0648\u0644 \u0645\u062e\u062a\u0627\u0631 (\u0635) \u0648 \u0622\u0644 \u0627\u0637\u0647\u0627\u0631 \u0622\u0646 \u062d\u0636\u0631\u062a \u0642\u0633\u0645 \u062f\u0627\u062f\u0645.\u0645\u0637\u0644\u0628 \u06a9\u0647 \u0628\u0647 \u0627\u06cc\u0646 \u062c\u0627 \u0631\u0633\u06cc\u062f\u060c \u0627\u0638\u0647\u0627\u0631 \u06a9\u0631\u062f\u0646\u062f: \u0645\u0627 \u0627\u0632 \u0645\u0644\u0627\u0632\u0645\u0627\u0646 \u062f\u0631\u06af\u0627\u0647 \u062d\u0636\u0631\u062a \u062d\u062c\u0651\u062a(\u0639\u062c) \u0647\u0633\u062a\u06cc\u0645.\u06cc\u06a9\u06cc \u0627\u0632 \u062c\u0645\u0639 \u0645\u0627 \u06a9\u0647 \u062f\u0631 \u062e\u062f\u0645\u062a \u0645\u0648\u0644\u0627\u06cc\u0645\u0627\u0646 \u0628\u0648\u062f\u060c \u0648\u0641\u0627\u062a \u06a9\u0631\u062f\u0647 \u0627\u0633\u062a\u060c \u0644\u0630\u0627 \u062d\u0636\u0631\u062a \u0645\u0627 \u0631\u0627 \u0645\u0623\u0645\u0648\u0631 \u0641\u0631\u0645\u0648\u062f\u0647&zwnj;\u0627\u0646\u062f \u06a9\u0647 \u0633\u062f\u0631 \u0648 \u06a9\u0627\u0641\u0648\u0631\u0634 \u0631\u0627 \u0627\u0632 \u062a\u0648 \u0628\u062e\u0631\u06cc\u0645.\u0647\u0645\u06cc\u0646 \u06a9\u0647 \u0627\u06cc\u0646 \u0645\u0637\u0644\u0628 \u0631\u0627 \u0634\u0646\u06cc\u062f\u0645\u060c \u062f\u0627\u0645\u0627\u0646 \u0627\u06cc\u0634\u0627\u0646 \u0631\u0627 \u0631\u0647\u0627 \u0646\u06a9\u0631\u062f\u0645 \u0648 \u062a\u0636\u0631\u0651\u0639 \u0648 \u0627\u0635\u0631\u0627\u0631 \u0632\u06cc\u0627\u062f\u06cc \u0646\u0645\u0648\u062f\u0645 \u06a9\u0647 \u0645\u0631\u0627 \u0647\u0645 \u0628\u0627 \u062e\u0648\u062f \u0628\u0628\u0631\u06cc\u062f.\u06af\u0641\u062a\u0646\u062f: \u0627\u06cc\u0646 \u06a9\u0627\u0631 \u0628\u0633\u062a\u0647 \u0628\u0647 \u0627\u062c\u0627\u0632\u0629 \u0622\u0646 \u0628\u0632\u0631\u06af\u0648\u0627\u0631 \u0627\u0633\u062a \u0648 \u0686\u0648\u0646 \u0627\u062c\u0627\u0632\u0647 \u0646\u0641\u0631\u0645\u0648\u062f\u0647&zwnj;\u0627\u0646\u062f\u060c \u062c\u0631\u0626\u062a \u0627\u06cc\u0646 \u062c\u0633\u0627\u0631\u062a \u0631\u0627 \u0646\u062f\u0627\u0631\u06cc\u0645.\u06af\u0641\u062a\u0645: \u0645\u0631\u0627 \u0628\u0647 \u0645\u062d\u0636\u0631 \u062d\u0636\u0631\u062a\u0634 \u0628\u0631\u0633\u0627\u0646\u06cc\u062f\u060c \u0628\u0639\u062f \u0647\u0645\u0627\u0646 \u062c\u0627\u060c \u0637\u0644\u0628 \u0631\u062e\u0635\u062a \u06a9\u0646\u06cc\u062f \u0627\u06af\u0631 \u0627\u062c\u0627\u0632\u0647 \u0641\u0631\u0645\u0648\u062f\u0646\u062f\u060c \u0634\u0631\u0641\u06cc\u0627\u0628 \u0645\u06cc&zwnj;\u0634\u0648\u0645 \u0648\u06af\u0631\u0646\u0647 \u0627\u0632 \u0647\u0645\u0627\u0646 \u062c\u0627 \u0628\u0631\u0645\u06cc&zwnj;\u06af\u0631\u062f\u0645 \u0648 \u062f\u0631 \u0627\u06cc\u0646 \u0635\u0648\u0631\u062a\u060c \u0647\u0645\u06cc\u0646 \u06a9\u0647 \u062f\u0631\u062e\u0648\u0627\u0633\u062a \u0645\u0631\u0627 \u0627\u062c\u0627\u0628\u062a \u06a9\u0631\u062f\u0647&zwnj;\u0627\u06cc\u062f \u062e\u062f\u0627\u06cc \u062a\u0639\u0627\u0644\u06cc \u0628\u0647 \u0634\u0645\u0627 \u0627\u062c\u0631 \u0648 \u067e\u0627\u062f\u0627\u0634 \u062e\u0648\u0627\u0647\u062f \u062f\u0627\u062f\u060c \u0648\u0644\u06cc \u0628\u0627\u0632 \u0647\u0645 \u0627\u0645\u062a\u0646\u0627\u0639 \u06a9\u0631\u062f\u0646\u062f.\u0628\u0627\u0644\u0627\u062e\u0631\u0647 \u0648\u0642\u062a\u06cc \u062a\u0636\u0631\u0651\u0639 \u0648 \u0627\u0635\u0631\u0627\u0631 \u0631\u0627 \u0627\u0632 \u062d\u062f \u06af\u0630\u0631\u0627\u0646\u062f\u0645\u060c \u0628\u0647 \u062d\u0627\u0644 \u0645\u0646 \u062a\u0631\u062d\u0651\u0645 \u0646\u0645\u0648\u062f\u0647 \u0648 \u0645\u0646\u0651\u062a \u06af\u0630\u0627\u0634\u062a\u0646\u062f \u0648 \u0642\u0628\u0648\u0644 \u06a9\u0631\u062f\u0646\u062f.\u0645\u0646 \u0647\u0645 \u0628\u0627 \u0639\u062c\u0644\u0647 \u062a\u0645\u0627\u0645 \u0633\u062f\u0631 \u0648 \u06a9\u0627\u0641\u0648\u0631 \u0631\u0627 \u062a\u062d\u0648\u06cc\u0644 \u062f\u0627\u062f\u0645 \u0648 \u062f\u06a9\u0651\u0627\u0646 \u0631\u0627 \u0628\u0633\u062a\u0645 \u0648 \u0628\u0627 \u0627\u06cc\u0634\u0627\u0646 \u0628\u0647 \u0631\u0627\u0647 \u0627\u0641\u062a\u0627\u062f\u0645\u060c \u062a\u0627 \u0622\u0646\u06a9\u0647 \u0628\u0647 \u0633\u0627\u062d\u0644 \u062f\u0631\u06cc\u0627 \u0631\u0633\u06cc\u062f\u06cc\u0645.\u0622\u0646\u0647\u0627 \u0628\u062f\u0648\u0646 \u0627\u06cc\u0646 \u06a9\u0647 \u0644\u0627\u0632\u0645 \u0628\u0627\u0634\u062f \u0628\u0647 \u06a9\u0634\u062a\u06cc \u0633\u0648\u0627\u0631 \u0634\u0648\u0646\u062f\u060c \u0628\u0631 \u0631\u0648\u06cc \u0622\u0628 \u0631\u0627\u0647 \u0627\u0641\u062a\u0627\u062f\u0646\u062f\u060c \u0648\u0644\u06cc \u0645\u0646 \u0627\u06cc\u0633\u062a\u0627\u062f\u0645.\u0645\u062a\u0648\u062c\u0651\u0647 \u0645\u0646 \u0634\u062f\u0646\u062f \u0648 \u06af\u0641\u062a\u0646\u062f: \u0646\u062a\u0631\u0633\u060c \u062e\u062f\u0627 \u0631\u0627 \u0628\u0647 \u062d\u0642\u0651 \u062d\u0636\u0631\u062a \u062d\u062c\u0651\u062a(\u0639\u062c) \u0642\u0633\u0645 \u0628\u062f\u0647 \u06a9\u0647 \u062a\u0648 \u0631\u0627 \u062d\u0641\u0638 \u06a9\u0646\u062f.\u0628\u0633\u0645 \u0627\u0644\u0644\u0651\u0647 \u0628\u06af\u0648 \u0648 \u0631\u0648\u0627\u0646\u0647 \u0634\u0648.\u0627\u06cc\u0646 \u062c\u0645\u0644\u0647 \u0631\u0627 \u06a9\u0647 \u0634\u0646\u06cc\u062f\u0645\u060c \u062e\u062f\u0627\u06cc \u0645\u062a\u0639\u0627\u0644 \u0631\u0627 \u0628\u0647 \u062d\u0642\u0651 \u062d\u0636\u0631\u062a \u062d\u062c\u0651\u062a \u0640 \u0627\u0631\u0648\u0627\u062d\u0646\u0627 \u0641\u062f\u0627\u0647 \u0640 \u0642\u0633\u0645 \u062f\u0627\u062f\u0645 \u0648 \u0628\u0631 \u0631\u0648\u06cc \u0622\u0628 \u0645\u0627\u0646\u0646\u062f \u0632\u0645\u06cc\u0646 \u062e\u0634\u06a9 \u0628\u0647 \u062f\u0646\u0628\u0627\u0644\u0634\u0627\u0646 \u0628\u0647 \u0631\u0627\u0647 \u0627\u0641\u062a\u0627\u062f\u0645 \u062a\u0627 \u0622\u0646 \u06a9\u0647 \u0628\u0647 \u0648\u0633\u0637 \u062f\u0631\u06cc\u0627 \u0631\u0633\u06cc\u062f\u06cc\u0645.\u0646\u0627\u06af\u0627\u0647 \u0627\u0628\u0631\u0647\u0627 \u0628\u0647 \u0647\u0645 \u067e\u06cc\u0648\u0633\u062a\u0646\u062f \u0648 \u0628\u0627\u0631\u0627\u0646 \u0634\u0631\u0648\u0639 \u0628\u0647 \u0628\u0627\u0631\u06cc\u062f\u0646 \u06a9\u0631\u062f.\u0627\u062a\u0651\u0641\u0627\u0642\u0627\u064b \u0645\u0646 \u062f\u0631 \u0648\u0642\u062a \u062e\u0631\u0648\u062c \u0627\u0632 \u0628\u0635\u0631\u0647\u060c \u0635\u0627\u0628\u0648\u0646\u06cc \u067e\u062e\u062a\u0647 \u0648 \u0622\u0646 \u0631\u0627 \u0628\u0631\u0627\u06cc \u062e\u0634\u06a9 \u0634\u062f\u0646 \u062f\u0631 \u0622\u0641\u062a\u0627\u0628\u060c \u0628\u0631 \u067e\u0634\u062a \u0628\u0627\u0645 \u06af\u0630\u0627\u0634\u062a\u0647 \u0628\u0648\u062f\u0645. \u0648\u0642\u062a\u06cc \u0628\u0627\u0631\u0627\u0646 \u0631\u0627 \u062f\u06cc\u062f\u0645\u060c \u0628\u0647 \u06cc\u0627\u062f \u0635\u0627\u0628\u0648\u0646&zwnj;\u0647\u0627 \u0627\u0641\u062a\u0627\u062f\u0645 \u0648 \u062e\u0627\u0637\u0631\u0645 \u067e\u0631\u06cc\u0634\u0627\u0646 \u0634\u062f.\u0628\u0647 \u0645\u062d\u0636 \u0627\u06cc\u0646 \u062e\u0637\u0648\u0631 \u0630\u0647\u0646\u06cc\u060c \u067e\u0627\u0647\u0627\u06cc\u0645 \u062f\u0631 \u0622\u0628 \u0641\u0631\u0648 \u0631\u0641\u062a\u060c \u0644\u0630\u0627 \u0645\u062c\u0628\u0648\u0631 \u0628\u0647 \u0634\u0646\u0627 \u06a9\u0631\u062f\u0646 \u0634\u062f\u0645 \u062a\u0627 \u062e\u0648\u062f \u0631\u0627 \u0627\u0632 \u063a\u0631\u0642 \u0634\u062f\u0646\u060c \u062d\u0641\u0638 \u06a9\u0646\u0645\u060c \u0648\u0644\u06cc \u0628\u0627 \u0647\u0645\u0647 \u0627\u06cc\u0646 \u0627\u062d\u0648\u0627\u0644 \u0627\u0632 \u0647\u0645\u0631\u0627\u0647\u0627\u0646 \u062f\u0648\u0631 \u0645\u06cc&zwnj;\u0645\u0627\u0646\u062f\u0645.\u0622\u0646\u0647\u0627 \u0648\u0642\u062a\u06cc \u0645\u062a\u0648\u062c\u0651\u0647 \u0645\u0646 \u0634\u062f\u0646\u062f \u0648 \u0645\u0631\u0627 \u0628\u0647 \u0622\u0646 \u062d\u0627\u0644\u062a \u062f\u06cc\u062f\u0646\u062f\u060c \u0628\u0631\u06af\u0634\u062a\u0646\u062f \u0648 \u062f\u0633\u062a \u0645\u0631\u0627 \u06af\u0631\u0641\u062a\u0646\u062f \u0648 \u0627\u0632 \u0622\u0628 \u0628\u06cc\u0631\u0648\u0646 \u06a9\u0634\u06cc\u062f\u0646\u062f \u0648 \u06af\u0641\u062a\u0646\u062f: \u0627\u0632 \u0622\u0646 \u062e\u0637\u0648\u0631 \u0630\u0647\u0646\u06cc \u06a9\u0647 \u0628\u0647 \u0641\u06a9\u0631\u062a \u0631\u0633\u06cc\u062f\u060c \u062a\u0648\u0628\u0647 \u06a9\u0646 \u0648 \u0645\u062c\u062f\u0651\u062f\u0627\u064b \u062e\u062f\u0627\u06cc \u062a\u0639\u0627\u0644\u06cc \u0631\u0627 \u0628\u0647 \u062d\u0636\u0631\u062a \u062d\u062c\u0651\u062a(\u0639\u062c) \u0642\u0633\u0645 \u0628\u062f\u0647.\u0645\u0646 \u0647\u0645 \u062a\u0648\u0628\u0647 \u06a9\u0631\u062f\u0645 \u0648 \u062f\u0648\u0628\u0627\u0631\u0647 \u062e\u062f\u0627 \u0631\u0627 \u0628\u0647 \u062d\u0642\u0651 \u062d\u0636\u0631\u062a \u062d\u062c\u0651\u062a(\u0639\u062c) \u0642\u0633\u0645 \u062f\u0627\u062f\u0645 \u0648 \u0628\u0631 \u0631\u0648\u06cc \u0622\u0628 \u0631\u0627\u0647\u06cc \u0634\u062f\u0645.\u0628\u0627\u0644\u0627\u062e\u0631\u0647 \u0628\u0647 \u0633\u0627\u062d\u0644 \u062f\u0631\u06cc\u0627 \u0631\u0633\u06cc\u062f\u06cc\u0645 \u0648 \u0627\u0632 \u0622\u0646\u062c\u0627 \u0647\u0645 \u0628\u0647 \u0637\u0631\u0641 \u0645\u0642\u0635\u062f\u060c \u0645\u0633\u06cc\u0631 \u0631\u0627 \u0627\u062f\u0627\u0645\u0647 \u062f\u0627\u062f\u06cc\u0645.\u0645\u0642\u062f\u0627\u0631\u06cc \u06a9\u0647 \u0631\u0641\u062a\u06cc\u0645 \u062f\u0631 \u062f\u0627\u0645\u0646\u0647 \u0628\u06cc\u0627\u0628\u0627\u0646\u060c \u0686\u0627\u062f\u0631\u06cc \u0628\u0647 \u0686\u0634\u0645 \u0645\u06cc&zwnj;\u062e\u0648\u0631\u062f \u06a9\u0647 \u0646\u0648\u0631 \u0622\u0646\u060c \u0641\u0636\u0627 \u0631\u0627 \u0631\u0648\u0634\u0646 \u0646\u0645\u0648\u062f\u0647 \u0628\u0648\u062f.\u0647\u0645\u0631\u0627\u0647\u0627\u0646 \u06af\u0641\u062a\u0646\u062f: \u062a\u0645\u0627\u0645 \u0645\u0642\u0635\u0648\u062f\u060c \u062f\u0631 \u0627\u06cc\u0646 \u062e\u06cc\u0645\u0647 \u0627\u0633\u062a \u0648 \u0628\u0627 \u0622\u0646\u0647\u0627 \u062a\u0627 \u0646\u0632\u062f\u06cc\u06a9 \u0686\u0627\u062f\u0631 \u0631\u0641\u062a\u0645 \u0648 \u0647\u0645\u0627\u0646 \u062c\u0627 \u062a\u0648\u0642\u0651\u0641 \u06a9\u0631\u062f\u06cc\u0645.\u06cc\u06a9 \u0646\u0641\u0631 \u0627\u0632 \u0627\u06cc\u0634\u0627\u0646 \u0628\u0631\u0627\u06cc \u0627\u062c\u0627\u0632\u0647 \u06af\u0631\u0641\u062a\u0646 \u0648\u0627\u0631\u062f \u0634\u062f \u0648 \u062f\u0631\u0628\u0627\u0631\u0647 \u0622\u0648\u0631\u062f\u0646 \u0645\u0646 \u0628\u0627 \u062d\u0636\u0631\u062a \u0635\u062d\u0628\u062a \u06a9\u0631\u062f\u060c \u0628\u0647 \u0637\u0648\u0631\u06cc \u06a9\u0647 \u0633\u062e\u0646 \u0645\u0648\u0644\u0627\u06cc\u0645 \u0631\u0627 \u0634\u0646\u06cc\u062f\u0645\u060c \u0648\u0644\u06cc \u0627\u06cc\u0634\u0627\u0646 \u0631\u0627 \u0686\u0648\u0646 \u062f\u0627\u062e\u0644 \u0686\u0627\u062f\u0631 \u0628\u0648\u062f\u0646\u062f\u060c \u0646\u0645\u06cc&zwnj;\u062f\u06cc\u062f\u0645. \u062d\u0636\u0631\u062a \u0641\u0631\u0645\u0648\u062f\u0646\u062f: &laquo;\u0627\u0648 \u0631\u0627 \u0628\u0647 \u062c\u0627\u06cc \u062e\u0648\u062f \u0628\u0631\u06af\u0631\u062f\u0627\u0646\u06cc\u062f\u061b \u0632\u06cc\u0631\u0627 \u0627\u0648 \u0645\u0631\u062f\u06cc \u0627\u0633\u062a \u0635\u0627\u0628\u0648\u0646\u06cc&raquo;.\u0627\u06cc\u0646 \u062c\u0645\u0644\u0647 \u062d\u0636\u0631\u062a\u060c \u0627\u0634\u0627\u0631\u0647 \u0628\u0647 \u062e\u0637\u0648\u0631 \u0630\u0647\u0646\u06cc \u0645\u0646 \u062f\u0631 \u0645\u0648\u0631\u062f \u0635\u0627\u0628\u0648\u0646 \u0628\u0648\u062f\u060c \u06cc\u0639\u0646\u06cc \u0647\u0646\u0648\u0632 \u062f\u0644 \u0631\u0627 \u0627\u0632 \u0648\u0627\u0628\u0633\u062a\u06af\u06cc&zwnj;\u0647\u0627\u06cc \u062f\u0646\u06cc\u0648\u06cc \u062e\u0627\u0644\u06cc \u0646\u06a9\u0631\u062f\u0647 \u0627\u0633\u062a \u062a\u0627 \u0645\u062d\u0628\u0651\u062a \u0645\u062d\u0628\u0648\u0628 \u0648\u0627\u0642\u0639\u06cc \u0631\u0627 \u062f\u0631 \u0622\u0646 \u062c\u0627\u06cc \u062f\u0647\u062f \u0648 \u0634\u0627\u06cc\u0633\u062a\u06af\u06cc \u0647\u0645\u0646\u0634\u06cc\u0646\u06cc \u0628\u0627 \u062f\u0648\u0633\u062a\u0627\u0646 \u062e\u062f\u0627 \u0631\u0627 \u0646\u062f\u0627\u0631\u062f.\u0627\u06cc\u0646 \u0633\u062e\u0646 \u0631\u0627 \u06a9\u0647 \u0634\u0646\u06cc\u062f\u0645 \u0648 \u0622\u0646 \u0631\u0627 \u0628\u0631 \u0637\u0628\u0642 \u0628\u0631\u0647\u0627\u0646 \u0639\u0642\u0644\u06cc \u0648 \u0634\u0631\u0639\u06cc \u062f\u06cc\u062f\u0645\u060c \u062f\u0646\u062f\u0627\u0646 \u0627\u06cc\u0646 \u0637\u0645\u0639 \u0631\u0627 \u06a9\u0646\u062f\u0647 \u0648 \u0686\u0634\u0645 \u0627\u0632 \u0627\u06cc\u0646 \u0622\u0631\u0632\u0648 \u067e\u0648\u0634\u06cc\u062f\u0645 \u0648 \u062f\u0627\u0646\u0633\u062a\u0645 \u062a\u0627 \u0632\u0645\u0627\u0646\u06cc \u06a9\u0647 \u0622\u06cc\u0646\u0647 \u062f\u0644\u060c \u0628\u0647 \u062a\u06cc\u0631\u06af\u06cc&zwnj;\u0647\u0627\u06cc \u062f\u0646\u06cc\u0648\u06cc \u0622\u0644\u0648\u062f\u0647 \u0627\u0633\u062a\u060c \u0686\u0647\u0631\u0647 \u0645\u062d\u0628\u0648\u0628 \u062f\u0631 \u0622\u0646 \u0645\u0646\u0639\u06a9\u0633 \u0646\u0645\u06cc&zwnj;\u0634\u0648\u062f \u0648 \u0635\u0648\u0631\u062a\u06cc \u0645\u0637\u0644\u0648\u0628\u060c \u062f\u0631 \u0622\u0646 \u062f\u06cc\u062f\u0647 \u0646\u062e\u0648\u0627\u0647\u062f \u0634\u062f \u0686\u0647 \u0631\u0633\u062f \u0628\u0647 \u0627\u06cc\u0646 \u06a9\u0647 \u062f\u0631 \u062e\u062f\u0645\u062a \u0648 \u0645\u0644\u0627\u0632\u0645\u062a \u0622\u0646 \u062d\u0636\u0631\u062a \u0628\u0627\u0634\u062f.<br \/>\n\u067e\u064a \u0646\u0648\u0634\u062a \u0647\u0627 :<\/p>\n<p>\u0627\u0644\u0639\u0628\u0642\u0631\u06cc \u0627\u0644\u062d\u0633\u0627\u0646 \u062c\u0644\u062f 2 \u0635 134 \u0633 42 \u0645\u0646\u0628\u0639:\u0645\u0627\u0647\u0646\u0627\u0645\u0647 \u0645\u0648\u0639\u0648\u062f \u0634\u0645\u0627\u0631\u0647 103.<br \/>\n&nbsp;<br \/>\n&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0634\u062e\u0635 \u0639\u0637\u0651\u0627\u0631\u06cc \u0627\u0632 \u0627\u0647\u0644 \u0628\u0635\u0631\u0647 \u0645\u06cc&zwnj;\u06af\u0648\u06cc\u062f: \u0631\u0648\u0632\u06cc \u062f\u0631 \u0645\u063a\u0627\u0632\u0629 \u0639\u0637\u0651\u0627\u0631\u06cc\u0645 \u0646\u0634\u0633\u062a\u0647 \u0628\u0648\u062f\u0645 \u06a9\u0647 \u062f\u0648 \u0646\u0641\u0631 \u0628\u0631\u0627\u06cc \u062e\u0631\u06cc\u062f\u0646 \u0633\u062f\u0631 \u0648 \u06a9\u0627\u0641\u0648\u0631 \u0628\u0647 \u062f\u06a9\u0651\u0627\u0646 \u0645\u0646 \u0648\u0627\u0631\u062f \u0634\u062f\u0646\u062f. \u0648\u0642\u062a\u06cc \u0628\u0647 \u0637\u0631\u0632 \u0635\u062d\u0628\u062a \u06a9\u0631\u062f\u0646 \u0648 \u0686\u0647\u0631\u0647&zwnj;\u0647\u0627\u06cc\u0634\u0627\u0646 \u062f\u0642\u0651\u062a \u06a9\u0631\u062f\u0645\u060c \u0645\u062a\u0648\u062c\u0651\u0647 \u0634\u062f\u0645 \u06a9\u0647 \u0627\u0647\u0644 \u0628\u0635\u0631\u0647 \u0648 \u0628\u0644\u06a9\u0647 \u0627\u0632 \u0645\u0631\u062f\u0645 \u0645\u0639\u0645\u0648\u0644\u06cc \u0646\u06cc\u0633\u062a\u0646\u062f \u0628\u0647 \u0647\u0645\u06cc\u0646 \u062c\u0647\u062a \u0627\u0632 \u0634\u0647\u0631 \u0648 \u062f\u06cc\u0627\u0631\u0634\u0627\u0646 \u067e\u0631\u0633\u06cc\u062f\u0645\u060c \u0648\u0644\u06cc \u062c\u0648\u0627\u0628\u06cc [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[],"tags":[312],"class_list":["post-7219","post","type-post","status-publish","format-standard","hentry","tag-312"],"acf":[],"_links":{"self":[{"href":"https:\/\/shiastudies.com\/fa\/wp-json\/wp\/v2\/posts\/7219","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/shiastudies.com\/fa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/shiastudies.com\/fa\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/shiastudies.com\/fa\/wp-json\/wp\/v2\/comments?post=7219"}],"version-history":[{"count":0,"href":"https:\/\/shiastudies.com\/fa\/wp-json\/wp\/v2\/posts\/7219\/revisions"}],"wp:attachment":[{"href":"https:\/\/shiastudies.com\/fa\/wp-json\/wp\/v2\/media?parent=7219"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/shiastudies.com\/fa\/wp-json\/wp\/v2\/categories?post=7219"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/shiastudies.com\/fa\/wp-json\/wp\/v2\/tags?post=7219"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}